{"id":12338,"date":"2022-10-31T14:18:23","date_gmt":"2022-10-31T14:18:23","guid":{"rendered":"https:\/\/www.medicalmate.net\/?p=12338"},"modified":"2022-10-31T14:18:23","modified_gmt":"2022-10-31T14:18:23","slug":"metodos-de-limpieza-de-gas-planta-de-incineracion-de-maishima-2","status":"publish","type":"post","link":"https:\/\/incinerators.hiclover.com\/index.php\/2022\/10\/31\/metodos-de-limpieza-de-gas-planta-de-incineracion-de-maishima-2\/","title":{"rendered":"M\u00e9todos de limpieza de gas Planta de incineraci\u00f3n de Maishima"},"content":{"rendered":"<div class=\"detail-item\" style=\"padding: 10px 20px; border-bottom-width: 1px; border-bottom-style: dashed; border-bottom-color: rgb(204, 204, 204); word-wrap: break-word; color: rgb(51, 51, 51); font-family: Arial, sans-serif; line-height: 18px;\">\n<h3 class=\"h3\" style=\"margin: 0px; padding: 0px; font-size: 14px;\">Informaci\u00f3n b\u00e1sica.<\/h3>\n<div class=\"sh-table\">\n<div class=\"tr\" style=\"overflow: hidden; zoom: 1; margin: 5px 0px;\"><span class=\"th\" style=\"float: left; width: 200px; font-weight: bold; text-align: right; padding-right: 10px; word-wrap: break-word;\">Mercados de exportaci\u00f3n:<\/span> <span class=\"td\" style=\"display: block; overflow: hidden; zoom: 1; word-wrap: break-word;\">Global<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"detail-item\" itemprop=\"description\" style=\"padding: 10px 20px; border-bottom-width: 1px; border-bottom-style: dashed; border-bottom-color: rgb(204, 204, 204); word-wrap: break-word; color: rgb(51, 51, 51); font-family: Arial, sans-serif; line-height: 18px;\">\n<h3 class=\"h3\" style=\"margin: 0px; padding: 0px; font-size: 14px;\">Descripci\u00f3n del producto<\/h3>\n<p style=\"margin: 0px 0px 10px;\">Caracter\u00edsticas principales:<br \/>\n* Todos los modelos con doble c\u00e1mara de combusti\u00f3n.<br \/>\n* Chimenea \/ chimenea de acero inoxidable, larga vida \u00fatil. * seg\u00fan pedido<br \/>\n* Alta temperatura, larga vida \u00fatil del incinerador.<br \/>\n* Instalaci\u00f3n gratuita o m\u00ednima en obra.<br \/>\n* Alta velocidad de combusti\u00f3n, de 10 kg a 500 kg por hora, hasta 6 toneladas por d\u00eda.<br \/>\n* Plano de control PLC. * seg\u00fan pedido<br \/>\n* Nuevo dise\u00f1o para el negocio de cremaci\u00f3n de animales de compa\u00f1\u00eda.<br \/>\n* Garant\u00eda de un a\u00f1o en incinerador y piezas en stock.<\/p>\n<p>\u00c1mbito de aplicaci\u00f3n:<br \/>\n1. Hospital y cl\u00ednica: Residuos I\u00e1tricos, Residuos Infecciosos, Vendajes, Biorresiduos, Medicina.<br \/>\n2. Matadero y hospital y granja de mascotas: animal muerto, biorresiduos.<br \/>\n3. Comunidad, puerto y estaci\u00f3n mar\u00edtima: residuos s\u00f3lidos urbanos, etc.<br \/>\n4. Laboratorios, ubicaciones remotas, operaciones de socorro en casos de desastre, cremaci\u00f3n de animales<\/p>\n<p>Nanjing Clover Medical Technology Co., Ltd. es un fabricante l\u00edder de incineradores de desechos en China. Somos fabricantes locales y uno de los mayores exportadores de China. El equipo t\u00e9cnico de incineraci\u00f3n pirol\u00edtica es el principal tratamiento de desechos en todo el mundo, para desechos m\u00e9dicos, incineraci\u00f3n de animales, cremaci\u00f3n de mascotas y otros wste s\u00f3lidos. La capacidad de 10kgs \/ Hr. Hasta 500kgs \/ Hr., Hasta 6ton por d\u00eda. Actualmente, planta de incineraci\u00f3n de residuos arabia saudita fabricante de tecnolog\u00eda de incineraci\u00f3n de residuos clover medical limited, capacidad del incinerador de residuos de 10 a 30 toneladas por d\u00eda, suministramos diferentes series para los requisitos de los clientes locales y dise\u00f1amos un incinerador actualizado con nuestra tecnolog\u00eda l\u00edder. La caracter\u00edstica de dise\u00f1o actualizado de nuestra gama de incineradores los convierte en uno de los m\u00e1s rentables del mundo.<\/p>\n<div id=\"StyleTableProd\" style=\"overflow: auto;\">\n<table style=\"border-collapse: collapse; border-spacing: 0px; width: 699px;\">\n<tbody>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Art\u00edculos \/ Modelo<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS10 (PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS20 (PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS30 (PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS50 (PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS100 (PLC)<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Velocidad de combusti\u00f3n<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10 kg \/ hora<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">20 kg \/ hora<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">30 kg \/ hora<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50 kg \/ hora<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100 kg \/ hora<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Capacidad de alimentaci\u00f3n<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">20 kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">40 kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">60kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100 kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">200 kilogramos<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Modo de control<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">SOCIEDAD AN\u00d3NIMA<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">SOCIEDAD AN\u00d3NIMA<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">SOCIEDAD AN\u00d3NIMA<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">SOCIEDAD AN\u00d3NIMA<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">SOCIEDAD AN\u00d3NIMA<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">C\u00e1mara de combusti\u00f3n<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">210L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">330L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">560L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">1200L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Dimensiones internas<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 50x50x40cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 65x65x50cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 75x75x60cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">El 100x80x70cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">El 120x100x100cm<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">C\u00e1mara secundaria<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">110L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">180L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">280L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">600L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">C\u00e1mara de filtro de humo<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Modo de alimentaci\u00f3n<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Voltaje<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220 V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220 V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220 V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220 V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220 V<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Energ\u00eda<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0,5 Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0,5 Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0,5 Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0,7 kilovatios<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0,7 kilovatios<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Consumo de aceite (kg \/ hora)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5,4-12,6<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">7,8\u201316,3<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10.2-20<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">12.1-24<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">14-28<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Consumo de gas (m3 \/ hora)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">6.2-11.4<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">8-15,7<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">9,8-20<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">9,9-26,1<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10\u201332,2<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Monitor de temperatura<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Protecci\u00f3n de temperatura<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Tanque de aceite<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">200L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Puerta de alimentaci\u00f3n<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 30x30cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 45x40cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 55x50cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 70x55cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Los 80x60cm<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Chimenea<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3 metros<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3 metros<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5 metros<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5 metros<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10 metros<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Tipo de chimenea<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Acero inoxidable<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Acero inoxidable<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Acero inoxidable<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Acero inoxidable<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Acero inoxidable<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n b\u00e1sica. Mercados de exportaci\u00f3n: Global Descripci\u00f3n del producto Caracter\u00edsticas principales: * Todos los modelos con doble c\u00e1mara de combusti\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":69,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[130],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts\/12338"}],"collection":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/comments?post=12338"}],"version-history":[{"count":0,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts\/12338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/media\/69"}],"wp:attachment":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/media?parent=12338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/categories?post=12338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/tags?post=12338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}