{"id":7020,"date":"2023-02-07T21:00:05","date_gmt":"2023-02-07T21:00:05","guid":{"rendered":"https:\/\/www.medicalmate.net\/?p=7020"},"modified":"2023-02-07T21:00:05","modified_gmt":"2023-02-07T21:00:05","slug":"pet-incinerator-3","status":"publish","type":"post","link":"https:\/\/incinerators.hiclover.com\/index.php\/2023\/02\/07\/pet-incinerator-3\/","title":{"rendered":"Pet Incinerator"},"content":{"rendered":"<div class=\"detail-item\" style=\"padding: 10px 20px; border-bottom-width: 1px; border-bottom-style: dashed; border-bottom-color: rgb(204, 204, 204); word-wrap: break-word; color: rgb(51, 51, 51); font-family: Arial, sans-serif; line-height: 18px;\">\n<h3 class=\"h3\" style=\"margin: 0px; padding: 0px; font-size: 14px;\">Basic Info.<\/h3>\n<div class=\"sh-table\">\n<div class=\"tr\" style=\"overflow: hidden; zoom: 1; margin: 5px 0px;\"><span class=\"th\" style=\"float: left; width: 200px; font-weight: bold; text-align: right; padding-right: 10px; word-wrap: break-word;\">Model NO.:<\/span><span class=\"td\" style=\"display: block; overflow: hidden; zoom: 1; word-wrap: break-word;\">pet incinerator manufacturers<\/span><\/div>\n<div class=\"tr\" style=\"overflow: hidden; zoom: 1; margin: 5px 0px;\"><span class=\"th\" style=\"float: left; width: 200px; font-weight: bold; text-align: right; padding-right: 10px; word-wrap: break-word;\">Export Markets:<\/span><span class=\"td\" style=\"display: block; overflow: hidden; zoom: 1; word-wrap: break-word;\">Global<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"detail-item\" itemprop=\"description\" style=\"padding: 10px 20px; border-bottom-width: 1px; border-bottom-style: dashed; border-bottom-color: rgb(204, 204, 204); word-wrap: break-word; color: rgb(51, 51, 51); font-family: Arial, sans-serif; line-height: 18px;\">\n<h3 class=\"h3\" style=\"margin: 0px; padding: 0px; font-size: 14px;\">Product Description<\/h3>\n<p style=\"margin: 0px 0px 10px;\">TS version PLC incinerator is latest layout for waste treatment, include health care waste, animal cremation and other solid waste. This equipment quality structural for types of site, such as hospital, environmental division, animal cremation services, etc&#8230; CLOVER diesel incinerator, diesel incinerator 50 kg\/hr, diesel livestock cremator, diesel medical incinerator, diesel medical incinerator provider in usa, diesel medical incinerators, Incinerator supply updated models with dual combustion space and smoke filter room having refractory lines, and the combustion room temperature up to 1200 deg C.&nbsp;<\/p>\n<p>Key Features:&nbsp; * All versions with Dual combustion room.&nbsp; * Stainless Steel chimney\/stack, long lifetime. *according to sequence * High fever, long lifetime of incinerator.&nbsp; * Free or minimum installation on site.&nbsp; * High burn rate, from 10kgs to 500kgs per hour, up to 6ton daily.&nbsp; *according to order&nbsp; New Design for pet animal cremation business.&nbsp; * One year guarantee on incinerator and components in stock.<\/p>\n<div id=\"StyleTableProd\" style=\"overflow: auto;\">\n<table style=\"border-collapse: collapse; border-spacing: 0px; width: 699px;\">\n<tbody>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Items\/Model<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS10(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS20(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS30(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS50(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS100(PLC)<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Burn Rate<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">20 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">30 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100 kg\/hour<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Feed Capacity<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">20kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">40kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">60kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">200 kg<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Control Mode<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Combustion Chamber<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">210L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">330L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">560L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">1200L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Internal Dimensions<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50x50x40cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">65x65x50cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">75x75x60cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100x80x70cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">120x100x100cm<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Secondary Chamber<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">110L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">180L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">280L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">600L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Smoke Filter Chamber<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Feed Mode<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Voltage<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Power<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.5Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.5Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.5Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.7Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.7Kw<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Oil Consumption (kg\/hour)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5.4\u201312.6<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">7.8\u201316.3<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10.2\u201320<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">12.1\u201324<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">14\u201328<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Gas Consumption (m3\/hour)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">6.2\u201311.4<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">8\u201315.7<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">9.8\u201320<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">9.9\u201326.1<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10\u201332.2<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Temperature Monitor<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Temperature Protection<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Oil Tank<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">200L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Feed Door<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">30x30cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">45x40cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">55x50cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">70x55cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">80x60cm<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Chimney<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10Meter<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Chimney Type<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Residency Time<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Gross Weight<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">1500kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2200kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3000kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">4500kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">6000kg<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">External Dimensions<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">140x90x120cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">160x110x130cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">175x120x140cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">230x130x155cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">260x150x180cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Basic Info. Model NO.:pet incinerator manufacturers Export Markets:Global Product Description TS version PLC incinerator is latest layout for waste treatment,<\/p>\n","protected":false},"author":1,"featured_media":61,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[129],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts\/7020"}],"collection":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/comments?post=7020"}],"version-history":[{"count":0,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts\/7020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/media\/61"}],"wp:attachment":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/media?parent=7020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/categories?post=7020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/tags?post=7020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}