{"id":7025,"date":"2023-02-18T15:20:40","date_gmt":"2023-02-18T15:20:40","guid":{"rendered":"https:\/\/www.medicalmate.net\/?p=7025"},"modified":"2023-02-18T15:20:40","modified_gmt":"2023-02-18T15:20:40","slug":"clover-medical-incinerators","status":"publish","type":"post","link":"https:\/\/incinerators.hiclover.com\/index.php\/2023\/02\/18\/clover-medical-incinerators\/","title":{"rendered":"Clover Medical Incinerators"},"content":{"rendered":"<h3 class=\"h3\" style=\"margin: 0px; padding: 0px; font-size: 14px; color: rgb(51, 51, 51); font-family: Arial, sans-serif;\">Product Description<\/h3>\n<p style=\"margin: 0px 0px 10px; color: rgb(51, 51, 51); font-family: Arial, sans-serif; line-height: 18px;\">\n<p>Nanjing Clover Medical Technology Co., Ltd., Neighborhood in Nanjing city, China.<\/p>\n<p>CLOVER supply medical equipment, medical waste incinerators, pet animal cremator, other solid waste treatment equipment, clean room equipment, fan filter units, air filter, etc.. We supply technology assistance, installation service and client produced.&nbsp;<\/p>\n<p>We&#8217;re one of the most significant waste incinerator producer and exporter of China. Pyrolytic incinerator specialized is primary waste treatment method all over the world, for Medical Waste, Animal Incineration, Pet cremation and other good waste. Currently we supply small and large scale incinerators as local client requirements and layout updated incinerator with our top technology.&nbsp;<\/p>\n<div id=\"StyleTableProd\" style=\"overflow: auto; color: rgb(51, 51, 51); font-family: Arial, sans-serif; line-height: 18px;\">\n<table style=\"border-collapse: collapse; border-spacing: 0px; width: 699px;\">\n<tbody>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Items\/Model<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS10(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS20(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS30(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS50(PLC)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">TS100(PLC)<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Burn Rate<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">20 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">30 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50 kg\/hour<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100 kg\/hour<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Feed Capacity<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">20kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">40kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">60kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">200 kg<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Control Mode<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">PLC<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Combustion Chamber<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">210L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">330L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">560L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">1200L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Internal Dimensions<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50x50x40cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">65x65x50cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">75x75x60cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100x80x70cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">120x100x100cm<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Secondary Chamber<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">50L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">110L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">180L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">280L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">600L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Smoke Filter Chamber<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Feed Mode<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Manual<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Voltage<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">220V<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Power<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.5Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.5Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.5Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.7Kw<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">0.7Kw<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Oil Consumption (kg\/hour)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5.4\u201312.6<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">7.8\u201316.3<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10.2\u201320<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">12.1\u201324<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">14\u201328<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Gas Consumption (m3\/hour)<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">6.2\u201311.4<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">8\u201315.7<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">9.8\u201320<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">9.9\u201326.1<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10\u201332.2<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Temperature Monitor<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Temperature Protection<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Yes<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Oil Tank<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">100L<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">200L<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Feed Door<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">30x30cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">45x40cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">55x50cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">70x55cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">80x60cm<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Chimney<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">5Meter<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">10Meter<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Chimney Type<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Stainless Steel<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">1st. Chamber Temperature<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2nd. Chamber Temperature<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">800degree\u20131000degree<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Residency Time<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2.0 Sec.<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">Gross Weight<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">1500kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">2200kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">3000kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">4500kg<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">6000kg<\/td>\n<\/tr>\n<tr>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">External Dimensions<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">140x90x120cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">160x110x130cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">175x120x140cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">230x130x155cm<\/td>\n<td style=\"margin: 0px; padding: 2px 5px; border-style: solid; border-color: rgb(153, 153, 153);\">260x150x180cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>Nanjing Clover Medical Technology Co., Ltd.&nbsp; Tel: +86-25-8461&nbsp;0201&nbsp; Fax: +86-25-8461&nbsp;0406<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Product Description Nanjing Clover Medical Technology Co., Ltd., Neighborhood in Nanjing city, China. CLOVER supply medical equipment, medical waste incinerators,<\/p>\n","protected":false},"author":1,"featured_media":82,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[129],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts\/7025"}],"collection":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/comments?post=7025"}],"version-history":[{"count":0,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/posts\/7025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/media\/82"}],"wp:attachment":[{"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/media?parent=7025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/categories?post=7025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incinerators.hiclover.com\/index.php\/wp-json\/wp\/v2\/tags?post=7025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}